{"id":15,"date":"2026-05-06T12:06:58","date_gmt":"2026-05-06T12:06:58","guid":{"rendered":"https:\/\/actividadesextraescolaresea.rkinformatika.online\/?page_id=15"},"modified":"2026-05-11T12:23:34","modified_gmt":"2026-05-11T12:23:34","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/actividadesextraescolaresea.com\/en\/aviso-legal\/","title":{"rendered":"Legal Notice"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"15\" class=\"elementor elementor-15\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-997acd6 elementor-section-height-default elementor-section-boxed elementor-section-height-default\" data-id=\"997acd6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ffc872e\" data-id=\"ffc872e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-050c1ad elementor-widget elementor-widget-text-editor\" data-id=\"050c1ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h1>AVISO LEGAL<\/h1><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">En cumplimiento de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico (LSSI CE), informamos a los usuarios de los datos y las condiciones de uso de<strong> Actividades Extra Escolares Estefania Alonso<\/strong><\/span><span lang=\"es-ES-u-co-trad\"><i><b>,\u00a0<\/b><\/i><\/span><span lang=\"es-ES-u-co-trad\">propietaria de esta web:<\/span><\/p><ul><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Denominaci\u00f3n Social: <strong>Estefan\u00eda Alonso Tom\u00e9<\/strong><\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Nombre comercial: <strong>Actividades Extra Escolares Estefania Alonso<\/strong><\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Domicilio Social:<strong> La Laguna, CP 38296<\/strong><\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">NIF:<strong> 78728883K<\/strong><\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Tel\u00e9fono: <strong>676 353 922<\/strong><\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">e-Mail: <strong>info@actividadesextraescolaresea.com<\/strong><\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Inscrita en el Registro Mercantil de , tomo , folio , hoja n\u00ba , Inscripci\u00f3n .<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Nombre de dominio:\u00a0<\/span><span lang=\"es-ES-u-co-trad\"><b>www.actividadesextraescolaresea.com<\/b><\/span><\/p><\/li><\/ul><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">El uso de esta web te da la condici\u00f3n de \u201cUsuario\u201d. Eso significa que aceptas los t\u00e9rminos y condiciones establecidos a continuaci\u00f3n y con ello te comprometes a no usarlo para fines ilegales.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><b>OBJETO<\/b><\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">A trav\u00e9s del Sitio Web, les ofrecemos a los Usuarios la posibilidad de acceder a la informaci\u00f3n sobre nuestros servicios y productos.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Toda persona que acceda a este sitio web asume el papel de usuario, comprometi\u00e9ndose a la observancia y cumplimiento riguroso de las disposiciones aqu\u00ed dispuestas, as\u00ed como a cualquier otra disposici\u00f3n legal que fuera de aplicaci\u00f3n.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><b>Estefan\u00eda Alonso Tom\u00e9 <\/b>se reserva el derecho a modificar cualquier tipo de informaci\u00f3n que pudiera aparecer en el sitio web, sin que exista obligaci\u00f3n de preavisar o poner en conocimiento de los usuarios dichas obligaciones, entendi\u00e9ndose como suficiente con la publicaci\u00f3n en el sitio web.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><b>CONDICIONES DE USO: OBLIGACIONES<\/b><\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">El Usuario se compromete a:<\/span><\/p><ol><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Hacer un uso adecuado y l\u00edcito del Espacio Web as\u00ed como de los contenidos y servicios, de conformidad con: (i) la legislaci\u00f3n aplicable en cada momento; (ii) las Condiciones Generales de Uso del Espacio Web; (iii) la moral y buenas costumbres generalmente aceptadas y (iv) el orden p\u00fablico.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Proveerse de todos los medios y requerimientos t\u00e9cnicos que se precisen para acceder al Espacio Web.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Facilitar informaci\u00f3n veraz al cumplimentar con sus datos de car\u00e1cter personal los formularios contenidos en el Espacio Web y a mantenerlos actualizados en todo momento de forma que responda, en cada momento, a la situaci\u00f3n real del Usuario. El Usuario ser\u00e1 el \u00fanico responsable de las manifestaciones falsas o inexactas que realice y de los perjuicios que cause a la empresa o a terceros por la informaci\u00f3n que facilite.<\/span><\/p><\/li><\/ol><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">No obstante, lo establecido en el apartado anterior el Usuario deber\u00e1 asimismo abstenerse de:<\/span><\/p><ol><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Hacer un uso no autorizado o fraudulento del Espacio Web y\/o de los contenidos con fines o efectos il\u00edcitos, prohibidos en las presentes Condiciones Generales de Uso, lesivos de los derechos e intereses de terceros, o que de cualquier forma puedan da\u00f1ar, inutilizar, sobrecargar, deteriorar o impedir la normal utilizaci\u00f3n de los servicios o los documentos, archivos y toda clase de contenidos almacenados en cualquier equipo inform\u00e1tico.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Acceder o intentar acceder a recursos o \u00e1reas restringidas del Espacio Web, sin cumplir las condiciones exigidas para dicho acceso.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Provocar da\u00f1os en los sistemas f\u00edsicos o l\u00f3gicos del Espacio Web, de sus proveedores o de terceros.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Introducir o difundir en la red virus inform\u00e1ticos o cualesquiera otros sistemas f\u00edsicos o l\u00f3gicos que sean susceptibles de provocar da\u00f1os en los sistemas f\u00edsicos o l\u00f3gicos de la empresa, proveedores o de terceros.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Intentar acceder, utilizar y\/o manipular los datos de la empresa, terceros proveedores y otros Usuarios.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Reproducir o copiar, distribuir, permitir el acceso del p\u00fablico a trav\u00e9s de cualquier modalidad de comunicaci\u00f3n p\u00fablica, transformar o modificar los contenidos, a menos que se cuente con la autorizaci\u00f3n del titular de los correspondientes derechos o ello resulte legalmente permitido.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Suprimir, ocultar o manipular las notas sobre derechos de propiedad intelectual o industrial y dem\u00e1s datos identificativos de los derechos de la empresa o de terceros incorporados a los contenidos, as\u00ed como los dispositivos t\u00e9cnicos de protecci\u00f3n o cualesquiera mecanismos de informaci\u00f3n que puedan insertarse en los contenidos.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Obtener e intentar obtener los contenidos empleando para ello medios o procedimientos distintos de los que, seg\u00fan los casos, se hayan puesto a su disposici\u00f3n a este efecto o se hayan indicado expresamente en las p\u00e1ginas web donde se encuentren los contenidos o, en general, de los que se empleen habitualmente en Internet por no entra\u00f1ar un riesgo de da\u00f1o o inutilizaci\u00f3n del Espacio web y\/o de los contenidos.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">En particular, y a t\u00edtulo meramente indicativo y no exhaustivo, el Usuario se compromete a no transmitir, difundir o poner a disposici\u00f3n de terceros informaciones, datos, contenidos, mensajes, gr\u00e1ficos, dibujos, archivos de sonido y\/o imagen, fotograf\u00edas, grabaciones, software y, en general, cualquier clase de material que: \u2022 De cualquier forma sea contrario, menosprecie o atente contra los derechos fundamentales y las libertades p\u00fablicas reconocidas constitucionalmente, en los Tratados Internacionales y en el resto de la legislaci\u00f3n vigente.\u2022 Induzca, incite o promueva actuaciones delictivas, denigratorias, difamatorias, violentas o, en general, contrarias a la ley, a la moral, a las buenas costumbres generalmente aceptadas o al orden p\u00fablico.\u2022 Induzca, incite o promueva actuaciones, actitudes o pensamientos discriminatorios por raz\u00f3n de sexo, raza, religi\u00f3n, creencias, edad o condici\u00f3n.\u2022 Incorpore, ponga a disposici\u00f3n o permita acceder a productos, elementos, mensajes y\/o servicios delictivos, violentos, ofensivos, nocivos, degradantes o, en general, contrarios a la ley, a la moral y a las buenas costumbres generalmente aceptadas o al orden p\u00fablico. Induzca o pueda inducir a un estado inaceptable de ansiedad o temor.\u2022 Induzca o incite a involucrarse en pr\u00e1cticas peligrosas, de riesgo o nocivas para la salud y el equilibrio ps\u00edquico.\u2022 Se encuentra protegido por la legislaci\u00f3n en materia de protecci\u00f3n intelectual o industrial perteneciente a la sociedad o a terceros sin que haya sido autorizado el uso que se pretenda realizar.\u2022 Sea contrario al honor, a la intimidad personal y familiar o a la propia imagen de las personas.\u2022 Constituya cualquier tipo de publicidad.\u2022 Incluya cualquier tipo de virus o programa que impida el normal funcionamiento del Espacio Web.<\/span><\/p><\/li><\/ol><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Si para acceder a algunos de los servicios y\/o contenidos del Espacio Web, se le proporcionara una contrase\u00f1a, se obliga a usarla de manera diligente, manteni\u00e9ndola en todo momento en secreto. En consecuencia, ser\u00e1 responsable de su adecuada custodia y confidencialidad, comprometi\u00e9ndose a no cederla a terceros, de manera temporal o permanente, ni a permitir el acceso a los mencionados servicios y\/o contenidos por parte de personas ajenas. Igualmente, se obliga a notificar a la sociedad cualquier hecho que pueda suponer un uso indebido de su contrase\u00f1a, como, a t\u00edtulo enunciativo, su robo, extrav\u00edo o el acceso no autorizado, con el fin de proceder a su inmediata cancelaci\u00f3n. En consecuencia, mientras no efect\u00fae la notificaci\u00f3n anterior, la empresa quedar\u00e1 eximida de cualquier responsabilidad que pudiera derivarse del uso indebido de su contrase\u00f1a, siendo de su responsabilidad cualquier utilizaci\u00f3n il\u00edcita de los contenidos y\/o servicios del Espacio Web por cualquier tercero ileg\u00edtimo. Si de manera negligente o dolosa incumpliera cualquiera de las obligaciones establecidas en las presentes Condiciones Generales de Uso, responder\u00e1 por todos los da\u00f1os y perjuicios que de dicho incumplimiento pudieran derivarse para la empresa.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><b>CONDICIONES DE USO: RESPONSABILIDADES<\/b><\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">No se garantiza el acceso continuado, ni la correcta visualizaci\u00f3n, descarga o utilidad de los elementos e informaciones contenidas en la web que puedan verse impedidos, dificultados o interrumpidos por factores o circunstancias que est\u00e1n fuera de su control. No se hace responsable de las decisiones que pudieran adoptarse como consecuencia del acceso a los contenidos o informaciones ofrecidas.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Se podr\u00e1 interrumpir el servicio, o resolver de modo inmediato la relaci\u00f3n con el Usuario, si se detecta que un uso de su Espacio Web, o de cualquiera de los servicios ofertados en el mismo, es contrario a las presentes Condiciones Generales de Uso. No nos hacemos responsables por da\u00f1os, perjuicios, p\u00e9rdidas, reclamaciones o gastos derivados del uso del Espacio Web.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">\u00danicamente ser\u00e1 responsable de eliminar, lo antes posible, los contenidos que puedan generar tales perjuicios, siempre que as\u00ed se notifique. En especial no seremos responsables de los perjuicios que se pudieran derivar, entre otros, de:<\/span><\/p><ol><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Interferencias, interrupciones, fallos, omisiones, aver\u00edas telef\u00f3nicas, retrasos, bloqueos o desconexiones en el funcionamiento del sistema electr\u00f3nico, motivadas por deficiencias, sobrecargas y errores en las l\u00edneas y redes de telecomunicaciones, o por cualquier otra causa ajena al control de la empresa.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Intromisiones ileg\u00edtimas mediante el uso de programas malignos de cualquier tipo y a trav\u00e9s de cualquier medio de comunicaci\u00f3n, tales como virus inform\u00e1ticos o cualesquiera otros.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Abuso indebido o inadecuado del Espacio Web.<\/span><\/p><\/li><li><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Errores de seguridad o navegaci\u00f3n producidos por un mal funcionamiento del navegador o por el uso de versiones no actualizadas del mismo. El administrador del espacio web se reservan el derecho de retirar, total o parcialmente, cualquier contenido o informaci\u00f3n presente en el Espacio Web.<\/span><\/p><\/li><\/ol><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">La empresa excluye cualquier responsabilidad por los da\u00f1os y perjuicios de toda naturaleza que pudieran deberse a la mala utilizaci\u00f3n de los servicios de libre disposici\u00f3n y uso por parte de los Usuarios de Espacio Web. Asimismo, queda exonerado de cualquier responsabilidad por el contenido e informaciones que puedan ser recibidas como consecuencia de los formularios de recogida de datos, estando los mismos \u00fanicamente para la prestaci\u00f3n de los servicios de consultas y dudas. Por otro lado, en caso de causar da\u00f1os y perjuicios por un uso il\u00edcito o incorrecto de dichos servicios, podr\u00e1 ser el Usuario reclamado por los da\u00f1os o perjuicios causados.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Usted mantendr\u00e1 a la empresa indemne frente a cualesquiera da\u00f1os y perjuicios que se deriven de reclamaciones, acciones o demandas de terceros como consecuencia de su acceso o uso del Espacio Web. Asimismo, usted se obliga a indemnizar frente a cualesquiera da\u00f1os y perjuicios, que se deriven del uso por su parte de \u201crobots\u201d, \u201cspiders\u201d, \u201ccrawlers\u201d o herramientas similares empleadas con el fin de recabar o extraer datos o de cualquier otra actuaci\u00f3n por su parte que imponga una carga irrazonable sobre el funcionamiento del Espacio Web.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><b>HIPERV\u00cdNCULOS<\/b><\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">El Usuario se obliga a no reproducir de ning\u00fan modo, ni siquiera mediante un hiperenlace o hiperv\u00ednculo, el Espacio Web, as\u00ed como ninguno de sus contenidos, salvo autorizaci\u00f3n expresa y por escrito del responsable del fichero.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">El Espacio Web puede incluir enlaces a otros espacios web, gestionados por terceros, con objeto de facilitar el acceso del Usuario a la informaci\u00f3n de empresas colaboradoras y\/o patrocinadoras. Conforme con ello, la sociedad no se responsabiliza del contenido de dichos Espacios web, ni se sit\u00faa en una posici\u00f3n de garante ni\/o de parte ofertante de los servicios y\/o informaci\u00f3n que se puedan ofrecer a terceros a trav\u00e9s de los enlaces de terceros.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Se concede al Usuario un derecho limitado, revocable y no exclusivo a crear enlaces a la p\u00e1gina principal del Espacio Web exclusivamente para uso privado y no comercial. Los Espacios web que incluyan enlace a nuestro Espacio Web (i) no podr\u00e1n falsear su relaci\u00f3n ni afirmar que se ha autorizado tal enlace, ni incluir marcas, denominaciones, nombres comerciales, logotipos u otros signos distintivos de nuestra sociedad; (ii) no podr\u00e1n incluir contenidos que puedan considerarse de mal gusto, obscenos, ofensivos, controvertidos, que inciten a la violencia o la discriminaci\u00f3n por raz\u00f3n de sexo, raza o religi\u00f3n, contrarios al orden p\u00fablico o il\u00edcitos; (iii) no podr\u00e1n enlazar a ninguna p\u00e1gina del Espacio Web distinta de la p\u00e1gina principal; (iv) deber\u00e1 enlazar con la propia direcci\u00f3n del Espacio Web, sin permitir que el Espacio web que realice el enlace reproduzca el Espacio Web como parte de su web o dentro de uno de sus \u201cframes\u201d o crear un \u201cbrowser\u201d sobre cualquiera de las p\u00e1ginas del Espacio Web. La empresa podr\u00e1 solicitar, en cualquier momento, que elimine cualquier enlace al Espacio Web, despu\u00e9s de lo cual deber\u00e1 proceder de inmediato a su eliminaci\u00f3n.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">La empresa no puede controlar la informaci\u00f3n, contenidos, productos o servicios facilitados por otros Espacios web que tengan establecidos enlaces con destino al Espacio Web.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><b>FUERZA MAYOR<\/b><\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">La empresa no ser\u00e1 responsable en todo en caso de imposibilidad de prestar servicio, si \u00e9sta se debe a interrupciones prolongadas del suministro el\u00e9ctrico, l\u00edneas de telecomunicaciones, conflictos sociales, huelgas, rebeli\u00f3n, explosiones, inundaciones, actos y omisiones del Gobierno, y en general todos los supuestos de fuerza mayor o de caso fortuito.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><b>PROPIEDAD INDUSTRIAL E INTELECTUAL<\/b><\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">El Usuario reconoce y acepta que todos los contenidos que se muestran en el Espacio Web y en especial, dise\u00f1os, textos, im\u00e1genes, logos, iconos, botones, software, nombres comerciales, marcas, o cualesquiera otros signos susceptibles de utilizaci\u00f3n industrial y\/o comercial est\u00e1n sujetos a derechos de Propiedad Intelectual y todas las marcas, nombres comerciales o signos distintivos, todos los derechos de propiedad industrial e intelectual, sobre los contenidos y\/o cualesquiera otros elementos insertados en el p\u00e1gina, que son propiedad exclusiva de la empresa y\/o de terceros, quienes tienen el derecho exclusivo de utilizarlos en el tr\u00e1fico econ\u00f3mico. Por todo ello el Usuario se compromete a no reproducir, copiar, distribuir, poner a disposici\u00f3n o de cualquier otra forma comunicar p\u00fablicamente, transformar o modificar tales contenidos manteniendo indemne a la empresa de cualquier reclamaci\u00f3n que se derive del incumplimiento de tales obligaciones. En ning\u00fan caso el acceso al Espacio Web implica ning\u00fan tipo de renuncia, transmisi\u00f3n, licencia o cesi\u00f3n total ni parcial de dichos derechos, salvo que se establezca expresamente lo contrario. Las presentes Condiciones Generales de Uso del Espacio Web no confieren a los Usuarios ning\u00fan otro derecho de utilizaci\u00f3n,\u00a0<a href=\"https:\/\/presencialismo.com\/\" target=\"_blank\" rel=\"noopener\">RRHH<\/a>, alteraci\u00f3n, explotaci\u00f3n, reproducci\u00f3n, distribuci\u00f3n o comunicaci\u00f3n p\u00fablica del Espacio Web y\/o de sus Contenidos distintos de los aqu\u00ed expresamente previstos. Cualquier otro uso o explotaci\u00f3n de cualesquiera derechos estar\u00e1 sujeto a la previa y expresa autorizaci\u00f3n espec\u00edficamente otorgada a tal efecto por la empresa o el tercero titular de los derechos afectados.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Los contenidos, textos, fotograf\u00edas, dise\u00f1os, logotipos, im\u00e1genes, programas de ordenador, c\u00f3digos fuente y, en general, cualquier creaci\u00f3n intelectual existente en este Espacio, as\u00ed como el propio Espacio en su conjunto, como obra art\u00edstica multimedia, est\u00e1n protegidos como derechos de autor por la legislaci\u00f3n en materia de propiedad intelectual. La empresa es titular de los elementos que integran el dise\u00f1o gr\u00e1fico del Espacio Web, lo men\u00fas, botones de navegaci\u00f3n, el c\u00f3digo HTML, los textos, im\u00e1genes, texturas, gr\u00e1ficos y cualquier otro contenido del Espacio Web o, en cualquier caso, dispone de la correspondiente autorizaci\u00f3n para la utilizaci\u00f3n de dichos elementos. El contenido dispuesto en el Espacio Web no podr\u00e1 ser reproducido ni en todo ni en parte, ni transmitido, ni registrado por ning\u00fan sistema de recuperaci\u00f3n de informaci\u00f3n, en ninguna forma ni en ning\u00fan medio, a menos que se cuente con la autorizaci\u00f3n previa, por escrito, de la citada Entidad.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Asimismo, queda prohibido suprimir, eludir y\/o manipular el \u00abcopyright\u00bb as\u00ed como los dispositivos t\u00e9cnicos de protecci\u00f3n, o cualesquiera mecanismos de informaci\u00f3n que pudieren contener los contenidos. El Usuario de este Espacio Web se compromete a respetar los derechos enunciados y a evitar cualquier actuaci\u00f3n que pudiera perjudicarlos, reserv\u00e1ndose en todo caso la empresa el ejercicio de cuantos medios o acciones legales le correspondan en defensa de sus leg\u00edtimos derechos de propiedad intelectual e industrial.<\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\"><b>LEY APLICABLE Y JURISDICCI\u00d3N<\/b><\/span><\/p><p align=\"justify\"><span lang=\"es-ES-u-co-trad\">Para la resoluci\u00f3n de todas las controversias o cuestiones relacionadas con el presente sitio web o de las actividades en \u00e9l desarrolladas, ser\u00e1 de aplicaci\u00f3n la legislaci\u00f3n espa\u00f1ola, a la que se someten expresamente las partes, siendo competentes para la resoluci\u00f3n de todos los conflictos derivados o relacionados con su uso los Juzgados y Tribunales del Pa\u00eds Vasco.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>AVISO LEGAL En cumplimiento de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico (LSSI CE), informamos a los usuarios de los datos y las condiciones de uso de Actividades Extra Escolares Estefania Alonso,\u00a0propietaria de esta web: Denominaci\u00f3n Social: Estefan\u00eda Alonso Tom\u00e9 Nombre comercial: Actividades Extra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-15","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aviso Legal - Actividades Extraescolares Estefan\u00eda Alonso<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/actividadesextraescolaresea.com\/en\/aviso-legal\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso Legal - Actividades Extraescolares Estefan\u00eda Alonso\" \/>\n<meta property=\"og:description\" content=\"AVISO LEGAL En cumplimiento de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico (LSSI CE), informamos a los usuarios de los datos y las condiciones de uso de Actividades Extra Escolares Estefania Alonso,\u00a0propietaria de esta web: Denominaci\u00f3n Social: Estefan\u00eda Alonso Tom\u00e9 Nombre comercial: Actividades Extra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/actividadesextraescolaresea.com\/en\/aviso-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Actividades Extraescolares Estefan\u00eda Alonso\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T12:23:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/aviso-legal\\\/\",\"url\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/aviso-legal\\\/\",\"name\":\"Aviso Legal - Actividades Extraescolares Estefan\u00eda Alonso\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/#website\"},\"datePublished\":\"2026-05-06T12:06:58+00:00\",\"dateModified\":\"2026-05-11T12:23:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/aviso-legal\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/actividadesextraescolaresea.com\\\/aviso-legal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/aviso-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aviso Legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/#website\",\"url\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/\",\"name\":\"Actividades Extraescolares Estefan\u00eda Alonso\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/#organization\",\"name\":\"Actividades Extraescolares Estefan\u00eda Alonso\",\"url\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-logonuevoweb.png\",\"contentUrl\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-logonuevoweb.png\",\"width\":1535,\"height\":605,\"caption\":\"Actividades Extraescolares Estefan\u00eda Alonso\"},\"image\":{\"@id\":\"https:\\\/\\\/actividadesextraescolaresea.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso Legal - Actividades Extraescolares Estefan\u00eda Alonso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/actividadesextraescolaresea.com\/en\/aviso-legal\/","og_locale":"en_GB","og_type":"article","og_title":"Aviso Legal - Actividades Extraescolares Estefan\u00eda Alonso","og_description":"AVISO LEGAL En cumplimiento de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico (LSSI CE), informamos a los usuarios de los datos y las condiciones de uso de Actividades Extra Escolares Estefania Alonso,\u00a0propietaria de esta web: Denominaci\u00f3n Social: Estefan\u00eda Alonso Tom\u00e9 Nombre comercial: Actividades Extra [&hellip;]","og_url":"https:\/\/actividadesextraescolaresea.com\/en\/aviso-legal\/","og_site_name":"Actividades Extraescolares Estefan\u00eda Alonso","article_modified_time":"2026-05-11T12:23:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/actividadesextraescolaresea.com\/aviso-legal\/","url":"https:\/\/actividadesextraescolaresea.com\/aviso-legal\/","name":"Aviso Legal - Actividades Extraescolares Estefan\u00eda Alonso","isPartOf":{"@id":"https:\/\/actividadesextraescolaresea.com\/#website"},"datePublished":"2026-05-06T12:06:58+00:00","dateModified":"2026-05-11T12:23:34+00:00","breadcrumb":{"@id":"https:\/\/actividadesextraescolaresea.com\/aviso-legal\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/actividadesextraescolaresea.com\/aviso-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/actividadesextraescolaresea.com\/aviso-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/actividadesextraescolaresea.com\/"},{"@type":"ListItem","position":2,"name":"Aviso Legal"}]},{"@type":"WebSite","@id":"https:\/\/actividadesextraescolaresea.com\/#website","url":"https:\/\/actividadesextraescolaresea.com\/","name":"Actividades Extraescolares Estefan\u00eda Alonso","description":"","publisher":{"@id":"https:\/\/actividadesextraescolaresea.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/actividadesextraescolaresea.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/actividadesextraescolaresea.com\/#organization","name":"Actividades Extraescolares Estefan\u00eda Alonso","url":"https:\/\/actividadesextraescolaresea.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/actividadesextraescolaresea.com\/#\/schema\/logo\/image\/","url":"https:\/\/actividadesextraescolaresea.com\/wp-content\/uploads\/2026\/05\/cropped-logonuevoweb.png","contentUrl":"https:\/\/actividadesextraescolaresea.com\/wp-content\/uploads\/2026\/05\/cropped-logonuevoweb.png","width":1535,"height":605,"caption":"Actividades Extraescolares Estefan\u00eda Alonso"},"image":{"@id":"https:\/\/actividadesextraescolaresea.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/actividadesextraescolaresea.com\/en\/wp-json\/wp\/v2\/pages\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actividadesextraescolaresea.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/actividadesextraescolaresea.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/actividadesextraescolaresea.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/actividadesextraescolaresea.com\/en\/wp-json\/wp\/v2\/comments?post=15"}],"version-history":[{"count":37,"href":"https:\/\/actividadesextraescolaresea.com\/en\/wp-json\/wp\/v2\/pages\/15\/revisions"}],"predecessor-version":[{"id":496,"href":"https:\/\/actividadesextraescolaresea.com\/en\/wp-json\/wp\/v2\/pages\/15\/revisions\/496"}],"wp:attachment":[{"href":"https:\/\/actividadesextraescolaresea.com\/en\/wp-json\/wp\/v2\/media?parent=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}